{"id":8275,"date":"2019-09-25T11:52:52","date_gmt":"2019-09-25T15:52:52","guid":{"rendered":"http:\/\/www.solidarityacrossborders.org\/?p=8275"},"modified":"2019-09-25T11:52:52","modified_gmt":"2019-09-25T15:52:52","slug":"3-oct-caravan-and-noise-demo-against-the-new-migrant-prison-in-laval","status":"publish","type":"post","link":"https:\/\/www.solidarityacrossborders.org\/es\/3-oct-caravan-and-noise-demo-against-the-new-migrant-prison-in-laval","title":{"rendered":"3 oct. Caravane et manif de bruit contre une nouvelle prison pour migrant.e.s \u00e0 Laval"},"content":{"rendered":"<p><a href=\"\/wp-content\/uploads\/Oct3-fb-banner-.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft size-medium wp-image-8276\" src=\"\/wp-content\/uploads\/Oct3-fb-banner--300x157.jpg\" alt=\"Oct3 - fb banner\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.solidarityacrossborders.org\/wp-content\/uploads\/Oct3-fb-banner--300x157.jpg 300w, https:\/\/www.solidarityacrossborders.org\/wp-content\/uploads\/Oct3-fb-banner--1024x536.jpg 1024w, https:\/\/www.solidarityacrossborders.org\/wp-content\/uploads\/Oct3-fb-banner-.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\u2026 <i>dans le cadre d&#8217;une journ\u00e9e d&#8217;actions multi-villes contre la d\u00e9tention de l&#8217;immigration au Canada<\/i> (<a href=\"https:\/\/www.facebook.com\/events\/2611360152420376\/\">liste compl\u00e8te ici<\/a>).<\/p>\n<p>Rejoignez-nous le 3 octobre \u00e0 Laval pour une manif de bruit familiale contre la nouvelle prison pour migrant.e.s! Apr\u00e8s un rassemblement devant les bureaux de l&#8217;ASFC au centre-ville, une caravane sillonnera Montr\u00e9al et s&#8217;arr\u00eatera dans diff\u00e9rents quartiers (Saint-Henri, C\u00f4te-des-Neiges, Parc-Ex et Montr\u00e9al-Nord) puis se dirigera vers une manif de bruit \u00e0 Laval \u00e0 16h30.<\/p>\n<p>Apportez vos casseroles, vos objets pour faire du bruit et \/ ou vos instruments! Apportez vos pancartes, vos banni\u00e8res et votre po\u00e9sie contre les fronti\u00e8res et les prisons, votre amour et votre rage! Il y aura de la nourriture et de la musique.<\/p>\n<p><b>Vous pouvez nous rejoindre:<\/b><\/p>\n<ul>\n<li>\u00c0 13h, devant les bureaux de l&#8217;ASFC, 1010 St. Antoine (m\u00e9tro Bonventure) pour rejoindre la caravane.<\/li>\n<li>\u00c0 16h au m\u00e9tro Henri-Bourassa pour prendre l\u2019autobus bus pour Laval.<\/li>\n<li>\u00c0 16h30 au Centre de d\u00e9tention de Laval, 200, Mont\u00e9e Saint-Fran\u00e7ois, pour la manif de bruit.<\/li>\n<\/ul>\n<p><b>NOTE : Si vous rejoignez la caravane ou prenez l&#8217;autobus vers Laval avec nous, <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSfs4982bBfJTmpiPRIxrJRm-omy1cf_1wC28PYl29P4f_zCvg\/viewform\">vous devez vous inscrire ici <\/a>avant le 2 octobre \u00e0 midi pour r\u00e9server une place et recevoir les derniers d\u00e9tails.<\/b><\/p>\n<p><b>Accessibilit\u00e9 et s\u00e9curit\u00e9<\/b> : pendant la caravane, des petits rassemblements auront lieu dans plusieurs quartiers, mais ils seront immobiles. Nous aurons de l&#8217;eau et de la nourriture pour tout le monde tout au long de la journ\u00e9e. Les organisateurs.trices tentent de rendre la manifestation \u00e0 Laval s\u00e9curitaire pour tout le monde, en particulier les plus touch\u00e9.e.s par le r\u00e9gime frontalier canadien. De plus, vous avez peut-\u00eatre entendu dire que SSF \u00e9tait sous le coup d\u2019une injonction l\u00e9gale. Toutefois, cette injonction ne s\u2019applique qu\u2019\u00e0 la propri\u00e9t\u00e9 de Tisseur situ\u00e9e \u00e0 Val-David (une ville au nord de Montr\u00e9al), et non \u00e0 Montr\u00e9al ou \u00e0 Laval. <a href=\"\/fr\/tisseur-turns-to-courts-in-bid-to-silence-critics-of-new-migrant-prison\">Plus ici<\/a>.<\/p>\n<p><b>Des questions ?<\/b> Vous pouvez nous \u00e9crire \u00e0 <a href=\"mailto:solidaritesansfrontieres@gmail.com\">solidaritesansfrontieres@gmail.com<\/a> ou nous appeler \u00e0 514 809 0773.<\/p>\n<p>Pour plus <a href=\"\/fr\/background-immigration-detention-in-canada-and-the-new-refugee-prison-in-laval\">d&#8217;informations sur la d\u00e9tention des migrant.e.s au Canada et la nouvelle prison<\/a> pour migrant.e.s.<\/p>\n<p>Pour en savoir plus sur les <a href=\"http:\/\/stopponslaprison.info\">entreprises impliqu\u00e9es dans la construction<\/a> de la nouvelle prison pour migrant.e.s de Laval.<\/p>\n<p>Signer <a href=\"\/fr\/no-to-a-new-prison-for-refugees-and-migrants-in-laval\">notre d\u00e9claration contre la prison<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u2026 dans le cadre d&#8217;une journ\u00e9e d&#8217;actions multi-villes contre la d\u00e9tention de l&#8217;immigration au Canada (liste compl\u00e8te ici). Rejoignez-nous le 3 octobre \u00e0 Laval pour une manif de bruit familiale contre la nouvelle prison pour migrant.e.s! Apr\u00e8s un rassemblement devant&hellip;<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.solidarityacrossborders.org\/es\/3-oct-caravan-and-noise-demo-against-the-new-migrant-prison-in-laval\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts\/8275"}],"collection":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/comments?post=8275"}],"version-history":[{"count":1,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts\/8275\/revisions"}],"predecessor-version":[{"id":8278,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts\/8275\/revisions\/8278"}],"wp:attachment":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/media?parent=8275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/categories?post=8275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/tags?post=8275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}