{"id":9225,"date":"2022-02-05T19:51:32","date_gmt":"2022-02-05T23:51:32","guid":{"rendered":"https:\/\/www.solidarityacrossborders.org\/?p=9225"},"modified":"2022-02-05T21:54:05","modified_gmt":"2022-02-06T01:54:05","slug":"borders-kill-cbsa-negligence-kills","status":"publish","type":"post","link":"https:\/\/www.solidarityacrossborders.org\/es\/borders-kill-cbsa-negligence-kills","title":{"rendered":"(Fran\u00e7ais) Les fronti\u00e8res tuent. La n\u00e9gligence de l\u2019ASFC tue: D\u00e9c\u00e8s au centre de surveillance de l\u2019immigration de Laval &#8211; Rage et deuil collectif"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/www.solidarityacrossborders.org\/fr\/wp-json\/wp\/v2\/posts\/9225\" class=\"qtranxs-available-language-link qtranxs-available-language-link-fr\" title=\"Fran\u00e7ais\">Franc\u00e9s<\/a> y <a href=\"https:\/\/www.solidarityacrossborders.org\/en\/wp-json\/wp\/v2\/posts\/9225\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">Ingl\u00e9s Estadounidense<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en Franc\u00e9s y Ingl\u00e9s Estadounidense.<\/p>\n<p class=\"more-link-p\"><a class=\"more-link\" href=\"https:\/\/www.solidarityacrossborders.org\/es\/borders-kill-cbsa-negligence-kills\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts\/9225"}],"collection":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/comments?post=9225"}],"version-history":[{"count":0,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/posts\/9225\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/media?parent=9225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/categories?post=9225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.solidarityacrossborders.org\/es\/wp-json\/wp\/v2\/tags?post=9225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}